{"id":98,"date":"2015-11-11T18:24:49","date_gmt":"2015-11-11T17:24:49","guid":{"rendered":"http:\/\/leblogdeconscience.com\/?p=98"},"modified":"2016-12-31T19:55:26","modified_gmt":"2016-12-31T18:55:26","slug":"la-revelations-des-pyramides","status":"publish","type":"post","link":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/","title":{"rendered":"La r\u00e9v\u00e9lation des pyramides"},"content":{"rendered":"<p>La r\u00e9v\u00e9lations des pyramides est un documentaire extraordinaire sur la <strong>construction\u00a0des <strong>pyramides<\/strong> en <strong>\u00c9gypte<\/strong><\/strong> et leurs v\u00e9ritables <strong>r\u00f4les<\/strong>, r\u00e9alis\u00e9 par Jacques GRIMAULT et Patrice POOYARD.<\/p>\n<p><a href=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-418 lazyload\" title=\"La r\u00e9v\u00e9lation des pyramides\" data-src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"217\" height=\"122\" data-srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg 853w\" data-sizes=\"(max-width: 217px) 100vw, 217px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 217px; --smush-placeholder-aspect-ratio: 217\/122;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-418\" title=\"La r\u00e9v\u00e9lation des pyramides\" src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"217\" height=\"122\" srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg 853w\" sizes=\"(max-width: 217px) 100vw, 217px\" \/><\/noscript><\/a> <a href=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-419 lazyload\" title=\"La r\u00e9v\u00e9lation des pyramides\" data-src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3-300x168.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"215\" height=\"121\" data-srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3-300x168.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3.jpg 853w\" data-sizes=\"(max-width: 215px) 100vw, 215px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 215px; --smush-placeholder-aspect-ratio: 215\/121;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-419\" title=\"La r\u00e9v\u00e9lation des pyramides\" src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3-300x168.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"215\" height=\"121\" srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3-300x168.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_3.jpg 853w\" sizes=\"(max-width: 215px) 100vw, 215px\" \/><\/noscript><\/a> <a href=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-420 lazyload\" title=\"La r\u00e9v\u00e9lation des pyramides\" data-src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2-300x168.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"214\" height=\"120\" data-srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2-300x168.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2.jpg 855w\" data-sizes=\"(max-width: 214px) 100vw, 214px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 214px; --smush-placeholder-aspect-ratio: 214\/120;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-420\" title=\"La r\u00e9v\u00e9lation des pyramides\" src=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2-300x168.jpg\" alt=\"La r\u00e9v\u00e9lation des pyramides\" width=\"214\" height=\"120\" srcset=\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2-300x168.jpg 300w, https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_2.jpg 855w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><\/noscript><\/a><\/p>\n<p>Il aborde les points suivants :<\/p>\n<ul>\n<li>Les <strong>techniques de constructions<\/strong> des pyramides sont <strong>bien plus \u00e9labor\u00e9es<\/strong> que ce que l&rsquo;on pensait jusqu&rsquo;\u00e0 pr\u00e9sent, avec une <strong>pr\u00e9cision millim\u00e9trique<\/strong> dans l&rsquo;<strong>assemblage des blocs de pierres<\/strong>.<\/li>\n<li>Il y a des<strong> construction similaires<\/strong> aux pyramides sur <strong>toute la plan\u00e8te<\/strong>, qui se trouvent align\u00e9s sur le m\u00eame axe.<\/li>\n<li>La grande pyramide de Kh\u00e9ops contient dans ses dimensions, tout en tas de <strong>donn\u00e9es math\u00e9matiques<\/strong>, qui ferait d&rsquo;elle un <strong>outil de transmission des connaissances<\/strong> au fil des \u00e2ges&#8230; supposant par la m\u00eame occasion que les anciennes civilisations avaient connaissance de ces donn\u00e9es avanc\u00e9es.<\/li>\n<li>Le site des pyramides, calqu\u00e9e sur des constellations, serait une sorte d&rsquo;<strong>horloge astronomique<\/strong> informant de la <strong>nature cyclo-cosmique du temps<\/strong>, et servirait a informer des \u00e9poques o\u00f9 allaient survenir de <strong>grands cataclysmes<\/strong> (cycle de pr\u00e9cession des \u00e9quinoxes).<\/li>\n<\/ul>\n<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><div  id=\"_ytid_11904\"  width=\"1200\" height=\"675\"  data-origwidth=\"1200\" data-origheight=\"675\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/JlBUkrhYS2s?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&modestbranding=0&rel=1&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/JlBUkrhYS2s\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/div><\/figure>\n<p>Commentaire personnel :<\/p>\n<p>Ce documentaire <strong>invalide<\/strong> donc compl\u00e8tement la <strong>vision lin\u00e9aire du temps<\/strong> que l&rsquo;on a avec une <strong>\u00e9volution constante<\/strong>. On prend conscience de la possibilit\u00e9 qu&rsquo;il puisse y avoir de grand cycles astronomiques qui prennent fin avec un grand cataclysme, et dont les anciennes civilisations avaient connaissances.<\/p>\n<p>Cela rejoint la cosmogonie de la <strong>tradition hindoue<\/strong>, et leur croyances en des <strong>cycles<\/strong> \u00ab\u00a0Yuga\u00a0\u00bb (allant de l&rsquo;\u00e2ge d&rsquo;or \u00e0 l&rsquo;\u00e2ge de fer) au cours desquels l&rsquo;homme <strong>n&rsquo;\u00e9volue pas<\/strong> mais <strong>d\u00e9g\u00e9n\u00e8re<\/strong> (l&rsquo;oppos\u00e9 de la vision lin\u00e9aire du temps avec la th\u00e9orie de l&rsquo;\u00e9volution). En attendant un article de ma part sur le sujet, vous pouvez aller voir de quoi il en retourne sur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kali_Yuga\">Wikipedia<\/a>.<\/p>\n<p>En compl\u00e9ment voici une conf\u00e9rence en 2 parties, tr\u00e8s int\u00e9ressante de Jacques Grimault intitul\u00e9 \u00ab\u00a0<em><strong>Une histoire cyclo-cosmique du monde<\/strong><\/em>\u00a0\u00bb :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=4FYigl9IXxY\">Une histoire cyclo-cosmique du monde 1\/2 <\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=n8dM29yv3EY\">Une histoire cyclo-cosmique du monde 2\/2<\/a><\/li>\n<\/ul>\n<p>Et \u00e9galement une \u00e9mission de 3 h 30 sur la libre antenne Meta TV o\u00f9 Jaques Grimault est l&rsquo;invit\u00e9 :<\/p>\n<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><div  id=\"_ytid_15085\"  width=\"1200\" height=\"675\"  data-origwidth=\"1200\" data-origheight=\"675\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/D8s8Sr3L8Ds?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&modestbranding=0&rel=1&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/D8s8Sr3L8Ds\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/div><\/figure>\n<p>&nbsp;<\/p>\n<h3>Livres sur le sujet :<\/h3>\n<ul>\n<li id=\"title\" class=\"a-size-large a-spacing-none\"><a href=\"https:\/\/www.amazon.fr\/cycle-lhumanit%C3%A9-adamique-Introduction-traditionnelle\/dp\/2844543960\/ref=as_sl_pc_tf_til?tag=leblogdecons-21&amp;linkCode=w00&amp;linkId=&amp;creativeASIN=2844543960\"><span id=\"productTitle\" class=\"a-size-large\">Le cycle de l&rsquo;humanit\u00e9 adamique : Introduction \u00e0 l&rsquo;\u00e9tude de la cyclologie traditionnelle<\/span><\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.amazon.fr\/cycle-lhumanit%C3%A9-adamique-Introduction-traditionnelle\/dp\/2844543960\/ref=as_sl_pc_tf_til?tag=leblogdecons-21&amp;linkCode=w00&amp;linkId=&amp;creativeASIN=2844543960\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone \" src=\"https:\/\/images-na.ssl-images-amazon.com\/images\/I\/51C6wPyFi3L._SX323_BO1,204,203,200_.jpg\" alt=\"Le cycle de l'humanit\u00e9 adamique\" width=\"262\" height=\"402\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9v\u00e9lations des pyramides est un documentaire extraordinaire sur la construction\u00a0des pyramides en \u00c9gypte et leurs v\u00e9ritables r\u00f4les, r\u00e9alis\u00e9 par Jacques GRIMAULT et Patrice POOYARD. Il aborde les points suivants : Les techniques de constructions des pyramides sont bien plus \u00e9labor\u00e9es que ce que l&rsquo;on pensait jusqu&rsquo;\u00e0 pr\u00e9sent, avec une pr\u00e9cision millim\u00e9trique dans l&rsquo;assemblage des &#8230; <a title=\"La r\u00e9v\u00e9lation des pyramides\" class=\"read-more\" href=\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\" aria-label=\"En savoir plus sur La r\u00e9v\u00e9lation des pyramides\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[10],"tags":[37,48,19,21],"class_list":["post-98","post","type-post","status-publish","format-video","hentry","category-documentaires-et-emissions","tag-construction","tag-egypte","tag-histoire","tag-revelations","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience<\/title>\n<meta name=\"description\" content=\"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience\" \/>\n<meta property=\"og:description\" content=\"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Conscience\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-11T17:24:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-31T18:55:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg\" \/>\n<meta name=\"author\" content=\"Conscience\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conscience\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\",\"url\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\",\"name\":\"La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience\",\"isPartOf\":{\"@id\":\"https:\/\/leblogdeconscience.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg\",\"datePublished\":\"2015-11-11T17:24:49+00:00\",\"dateModified\":\"2016-12-31T18:55:26+00:00\",\"author\":{\"@id\":\"https:\/\/leblogdeconscience.com\/#\/schema\/person\/85a55dd926c660dc71a9be7b411d2c0f\"},\"description\":\"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !\",\"breadcrumb\":{\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage\",\"url\":\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg\",\"contentUrl\":\"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg\",\"width\":853,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/leblogdeconscience.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9v\u00e9lation des pyramides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/leblogdeconscience.com\/#website\",\"url\":\"https:\/\/leblogdeconscience.com\/\",\"name\":\"Le blog de Conscience\",\"description\":\"A la recherche de la v\u00e9rit\u00e9, pour un autre regard sur le monde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/leblogdeconscience.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/leblogdeconscience.com\/#\/schema\/person\/85a55dd926c660dc71a9be7b411d2c0f\",\"name\":\"Conscience\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/leblogdeconscience.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/72ae192822435591198525527176d6d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/72ae192822435591198525527176d6d5?s=96&d=mm&r=g\",\"caption\":\"Conscience\"},\"sameAs\":[\"http:\/\/leblogdeconscience.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience","description":"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience","og_description":"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !","og_url":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/","og_site_name":"Le blog de Conscience","article_published_time":"2015-11-11T17:24:49+00:00","article_modified_time":"2016-12-31T18:55:26+00:00","og_image":[{"url":"http:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg"}],"author":"Conscience","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Conscience","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/","url":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/","name":"La r\u00e9v\u00e9lation des pyramides - Le blog de Conscience","isPartOf":{"@id":"https:\/\/leblogdeconscience.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage"},"image":{"@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage"},"thumbnailUrl":"http:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4-300x169.jpg","datePublished":"2015-11-11T17:24:49+00:00","dateModified":"2016-12-31T18:55:26+00:00","author":{"@id":"https:\/\/leblogdeconscience.com\/#\/schema\/person\/85a55dd926c660dc71a9be7b411d2c0f"},"description":"R\u00e9v\u00e9lations incroyables sur les pyramides : pr\u00e9cision de la construction, horloge astronomique, nature cyclo-cosmique du temps. Votre vision sera chang\u00e9e !","breadcrumb":{"@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#primaryimage","url":"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg","contentUrl":"https:\/\/leblogdeconscience.com\/wp-content\/uploads\/2015\/11\/lrdp_4.jpg","width":853,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/leblogdeconscience.com\/index.php\/2015\/11\/11\/la-revelations-des-pyramides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leblogdeconscience.com\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9v\u00e9lation des pyramides"}]},{"@type":"WebSite","@id":"https:\/\/leblogdeconscience.com\/#website","url":"https:\/\/leblogdeconscience.com\/","name":"Le blog de Conscience","description":"A la recherche de la v\u00e9rit\u00e9, pour un autre regard sur le monde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leblogdeconscience.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/leblogdeconscience.com\/#\/schema\/person\/85a55dd926c660dc71a9be7b411d2c0f","name":"Conscience","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leblogdeconscience.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/72ae192822435591198525527176d6d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ae192822435591198525527176d6d5?s=96&d=mm&r=g","caption":"Conscience"},"sameAs":["http:\/\/leblogdeconscience.com"]}]}},"_links":{"self":[{"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/posts\/98"}],"collection":[{"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":0,"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions"}],"wp:attachment":[{"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/media?parent=98"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/categories?post=98"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leblogdeconscience.com\/index.php\/wp-json\/wp\/v2\/tags?post=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}